{"id":2688,"count":3,"description":"Pair your meals with classic Italian sides. Easy, delicious, and versatile recipes using simple ingredients packed with flavor.","link":"https:\/\/www.laragazzacolmattarello.com\/en\/category\/recipes\/side-dishes\/","name":"Side dishes","slug":"side-dishes","taxonomy":"category","parent":389,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Side dishes Archives ~ La ragazza col mattarello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laragazzacolmattarello.com\/en\/category\/recipes\/side-dishes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Side dishes Archives ~ La ragazza col mattarello\" \/>\n<meta property=\"og:description\" content=\"Pair your meals with classic Italian sides. Easy, delicious, and versatile recipes using simple ingredients packed with flavor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laragazzacolmattarello.com\/en\/category\/recipes\/side-dishes\/\" \/>\n<meta property=\"og:site_name\" content=\"La ragazza col mattarello\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laragazzacolmattarello.com\/wp-content\/uploads\/2024\/01\/lrcm_logo_horiz_2023_1200x675.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mattarellogirl\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/category\\\/recipes\\\/side-dishes\\\/\",\"url\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/category\\\/recipes\\\/side-dishes\\\/\",\"name\":\"Side dishes Archives ~ La ragazza col mattarello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/category\\\/recipes\\\/side-dishes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/category\\\/recipes\\\/side-dishes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recipes\",\"item\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/category\\\/recipes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Side dishes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/\",\"name\":\"La ragazza col mattarello\",\"description\":\"Recetas tradicionales italianas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/#organization\",\"name\":\"La ragazza col mattarello\",\"alternateName\":\"Mia Villar Raurich\",\"url\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/la_ragazza_col_mattarello_512x512.png\",\"contentUrl\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/la_ragazza_col_mattarello_512x512.png\",\"width\":512,\"height\":512,\"caption\":\"La ragazza col mattarello\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laragazzacolmattarello.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laragazzacolmattarello\",\"https:\\\/\\\/x.com\\\/mattarellogirl\",\"https:\\\/\\\/www.instagram.com\\\/mattarellogirl\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/mattarellogirl\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@laragazzacolmattarello\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Side dishes Archives ~ La ragazza col mattarello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laragazzacolmattarello.com\/en\/category\/recipes\/side-dishes\/","og_locale":"en_US","og_type":"article","og_title":"Side dishes Archives ~ La ragazza col mattarello","og_description":"Pair your meals with classic Italian sides. Easy, delicious, and versatile recipes using simple ingredients packed with flavor.","og_url":"https:\/\/www.laragazzacolmattarello.com\/en\/category\/recipes\/side-dishes\/","og_site_name":"La ragazza col mattarello","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.laragazzacolmattarello.com\/wp-content\/uploads\/2024\/01\/lrcm_logo_horiz_2023_1200x675.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@mattarellogirl","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.laragazzacolmattarello.com\/en\/category\/recipes\/side-dishes\/","url":"https:\/\/www.laragazzacolmattarello.com\/en\/category\/recipes\/side-dishes\/","name":"Side dishes Archives ~ La ragazza col mattarello","isPartOf":{"@id":"https:\/\/www.laragazzacolmattarello.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.laragazzacolmattarello.com\/en\/category\/recipes\/side-dishes\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laragazzacolmattarello.com\/en\/category\/recipes\/side-dishes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.laragazzacolmattarello.com\/en\/"},{"@type":"ListItem","position":2,"name":"Recipes","item":"https:\/\/www.laragazzacolmattarello.com\/en\/category\/recipes\/"},{"@type":"ListItem","position":3,"name":"Side dishes"}]},{"@type":"WebSite","@id":"https:\/\/www.laragazzacolmattarello.com\/en\/#website","url":"https:\/\/www.laragazzacolmattarello.com\/en\/","name":"La ragazza col mattarello","description":"Recetas tradicionales italianas","publisher":{"@id":"https:\/\/www.laragazzacolmattarello.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laragazzacolmattarello.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.laragazzacolmattarello.com\/en\/#organization","name":"La ragazza col mattarello","alternateName":"Mia Villar Raurich","url":"https:\/\/www.laragazzacolmattarello.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.laragazzacolmattarello.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.laragazzacolmattarello.com\/wp-content\/uploads\/2026\/05\/la_ragazza_col_mattarello_512x512.png","contentUrl":"https:\/\/www.laragazzacolmattarello.com\/wp-content\/uploads\/2026\/05\/la_ragazza_col_mattarello_512x512.png","width":512,"height":512,"caption":"La ragazza col mattarello"},"image":{"@id":"https:\/\/www.laragazzacolmattarello.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laragazzacolmattarello","https:\/\/x.com\/mattarellogirl","https:\/\/www.instagram.com\/mattarellogirl\/","https:\/\/www.pinterest.com\/mattarellogirl\/","https:\/\/www.youtube.com\/@laragazzacolmattarello"]}]}},"_links":{"self":[{"href":"https:\/\/www.laragazzacolmattarello.com\/en\/wp-json\/wp\/v2\/categories\/2688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laragazzacolmattarello.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.laragazzacolmattarello.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.laragazzacolmattarello.com\/en\/wp-json\/wp\/v2\/categories\/389"}],"wp:post_type":[{"href":"https:\/\/www.laragazzacolmattarello.com\/en\/wp-json\/wp\/v2\/posts?categories=2688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}